{"id":235,"count":19,"description":"","link":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/","name":"Tenerife","slug":"tenerife-it","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tenerife - CheckedHolidays<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tenerife - CheckedHolidays\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/\" \/>\n<meta property=\"og:site_name\" content=\"CheckedHolidays\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@checkedholidays\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/guide\\\/tenerife-it\\\/\",\"url\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/guide\\\/tenerife-it\\\/\",\"name\":\"Tenerife - CheckedHolidays\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/guide\\\/tenerife-it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/guide\\\/tenerife-it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tenerife\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/\",\"name\":\"CheckedHolidays\",\"description\":\"Spanish island holidays... but better!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.checkedholidays.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tenerife - CheckedHolidays","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/","og_locale":"it_IT","og_type":"article","og_title":"Tenerife - CheckedHolidays","og_url":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/","og_site_name":"CheckedHolidays","twitter_card":"summary_large_image","twitter_site":"@checkedholidays","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/","url":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/","name":"Tenerife - CheckedHolidays","isPartOf":{"@id":"https:\/\/www.checkedholidays.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.checkedholidays.com\/it\/guide\/tenerife-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.checkedholidays.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tenerife"}]},{"@type":"WebSite","@id":"https:\/\/www.checkedholidays.com\/it\/#website","url":"https:\/\/www.checkedholidays.com\/it\/","name":"CheckedHolidays","description":"Spanish island holidays... but better!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.checkedholidays.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.checkedholidays.com\/it\/wp-json\/wp\/v2\/categories\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.checkedholidays.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.checkedholidays.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.checkedholidays.com\/it\/wp-json\/wp\/v2\/posts?categories=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}